{"id":5536,"date":"2024-04-19T10:58:30","date_gmt":"2024-04-19T14:58:30","guid":{"rendered":"https:\/\/www.cheapoair.ca\/getting-there\/?p=5536"},"modified":"2024-04-19T10:58:30","modified_gmt":"2024-04-19T14:58:30","slug":"au-dela-des-haikus-reflexion-sur-de-beaux-exemples-de-poesie-japonaise","status":"publish","type":"post","link":"https:\/\/www.cheapoair.ca\/getting-there\/au-dela-des-haikus-reflexion-sur-de-beaux-exemples-de-poesie-japonaise\/","title":{"rendered":"Au-del\u00e0 des ha\u00efkus : R\u00e9flexion sur de beaux exemples de po\u00e9sie japonaise.\u00a0"},"content":{"rendered":"<p><span data-contrast=\"none\">Le Japon est l&#8217;un des plus grands bastions d&#8217;expression culturelle et artistique au monde. L&#8217;une des prouesses artistiques les plus reconnaissables de la culture japonaise est la po\u00e9sie, un art qui \u00e9volue et se perfectionne depuis plus de mille ans. Si le ha\u00efku est la forme la plus connue de la po\u00e9sie japonaise, ce genre ne cesse d&#8217;\u00e9voluer, englobant une multitude de styles et de techniques de narration diff\u00e9rents. Fortement influenc\u00e9 par la tradition bouddhiste zen, cet art est souvent l\u00e9ger et a\u00e9rien, se concentrant sur des th\u00e8mes aussi divers que le premier amour, la beaut\u00e9 de la nature et la joie des moments brefs et solitaires.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Plongeons dans les formes les plus significatives de la po\u00e9sie japonaise et voyons comment les meilleurs scribes du Japon utilisent la r\u00e9daction et le style pour cr\u00e9er des \u0153uvres litt\u00e9raires riches de sens et d&#8217;inspiration.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<h2>Haiku<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5437 size-full\" src=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_64358950.jpg\" alt=\"Elderly couple writing haikus\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_64358950.jpg 1000w, https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_64358950-300x180.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span data-contrast=\"none\">Les ha\u00efkus, l&#8217;une des formes les plus populaires de po\u00e9sie en format court, sont \u00e9crits en trois lignes et suivent souvent le mod\u00e8le de syllabes 5-7-5. Utilis\u00e9s \u00e0 l&#8217;origine comme premiers vers de po\u00e8mes plus importants appel\u00e9s renga, les ha\u00efkus sont devenus un style majeur de la po\u00e9sie japonaise au XVIe si\u00e8cle. Magnifiques et pertinents, les ha\u00efkus sont riches en couleurs et en images et se concentrent sur les petits moments fugaces pr\u00e9sents dans la nature pour cr\u00e9er un instantan\u00e9 vivant du monde.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Matsuyama, une ville de la pr\u00e9fecture d&#8217;Ehime, est devenue une destination de choix pour les amateurs de po\u00e9sie qui souhaitent se plonger dans l&#8217;histoire des ha\u00efkus. Matsuyama \u00e9tait le lieu de vie du po\u00e8te Masaoka Shiki au XIXe si\u00e8cle, l&#8217;une des principales figures \u00e0 l&#8217;origine du d\u00e9veloppement du ha\u00efku moderne. La maison de Shiki est aujourd&#8217;hui un monument historique et un mus\u00e9e, o\u00f9 sont expos\u00e9s son bureau personnel et certains\u00a0de ses souvenirs familiaux les plus marquants. En plus d&#8217;en apprendre davantage sur Shiki et sur l&#8217;essor du ha\u00efku, vous pouvez \u00e9galement vous laisser tenter par d&#8217;autres activit\u00e9s touristiques dynamiques de la r\u00e9gion, notamment des panoramas naturels sur l&#8217;\u00e9poustouflante mer int\u00e9rieure de Seto et la visite du\u00a0<\/span><a href=\"https:\/\/www.japan.travel\/en\/spot\/819\/\"><span data-contrast=\"none\">ch\u00e2teau de Matsuyama<\/span><\/a><span data-contrast=\"none\">, un \u00e9difice datant du XVIIe si\u00e8cle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<h2>Tanka<\/h2>\n<p><span data-contrast=\"none\">Beau et enracin\u00e9 dans une \u00e9motion profonde, le tanka ajoute deux lignes suppl\u00e9mentaires au format traditionnel du ha\u00efku, en utilisant un sch\u00e9ma de syllabes 5-7-5-7-7. Ces vers suppl\u00e9mentaires permettent aux tankas d&#8217;\u00eatre une forme privil\u00e9gi\u00e9e d&#8217;expression romantique. Depuis leur origine au VIIe si\u00e8cle, les tankas ont \u00e9t\u00e9 utilis\u00e9s par les couples pour communiquer discr\u00e8tement leurs sentiments les plus profonds. Le tanka \u00e9tait \u00e9galement tr\u00e8s pris\u00e9 \u00e0 la cour imp\u00e9riale japonaise. Les nobles vivant \u00e0 l&#8217;\u00e9poque du Japon classique participaient souvent \u00e0 des concours d&#8217;\u00e9criture de tanka, s&#8217;attirant les faveurs des seigneurs de haut rang gr\u00e2ce \u00e0 leur habilet\u00e9 en mati\u00e8re de prose. On trouve de nombreux exemples de\u00a0tanka dans le Manyoshu, le plus ancien recueil de po\u00e9sie japonaise, qui date de 759 apr\u00e8s J\u00e9sus-Christ.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Refl\u00e9tant les origines du style \u00e0 la cour imp\u00e9riale japonaise, le tanka est \u00e9troitement li\u00e9 \u00e0 Nara, la capitale du Japon \u00e0 l&#8217;\u00e9poque classique. Parmi les destinations les plus pris\u00e9es des amateurs de po\u00e9sie \u00e0 Nara figure le\u00a0<\/span><a href=\"https:\/\/www.japan.travel\/en\/spot\/998\/\"><span data-contrast=\"none\">palais Heijo<\/span><\/a><span data-contrast=\"none\">, un site class\u00e9 au patrimoine mondial de l&#8217;UNESCO qui plonge les visiteurs dans l&#8217;histoire des premiers souverains du Japon.<\/span><span data-contrast=\"none\">\u00a0<\/span><span data-contrast=\"none\">\u00c0 noter \u00e9galement le jardin Isui-en, l&#8217;un des plus beaux jardins du Japon, qui abrite des arbres \u00e0 fleurs \u00e0 couper le souffle et permet un acc\u00e8s ais\u00e9 \u00e0 certains des temples les plus c\u00e9l\u00e8bres de Nara.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<h2>Renga<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5438 size-full\" src=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_2410892839.jpg\" alt=\"Japanese calligraphy\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_2410892839.jpg 1000w, https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_2410892839-300x180.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span data-contrast=\"none\">Forme de po\u00e9sie collaborative, les rengas sont compos\u00e9es par deux ou plusieurs po\u00e8tes qui \u00e9crivent alternativement des strophes selon le format 5-7-5 et 7-7. Afin d&#8217;obtenir un certain degr\u00e9 de coh\u00e9rence dans l&#8217;\u0153uvre, les po\u00e8tes appuient leur composition sur la strophe pr\u00e9c\u00e9dente, cr\u00e9ant ainsi une cha\u00eene unifi\u00e9e tout au long de l&#8217;\u0153uvre. Beaucoup plus long que les autres formes de po\u00e9sie japonaise, le renga est g\u00e9n\u00e9ralement \u00e9crit dans une composition de 36 lignes appel\u00e9e kasen, bien que certains se poursuivent sur des centaines de lignes. Populaire \u00e0 l&#8217;\u00e9poque m\u00e9di\u00e9vale, le renga aborde de nombreux th\u00e8mes, dont la nature et le changement des saisons.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Si\u00e8ge du pouvoir imp\u00e9rial japonais \u00e0 l&#8217;\u00e9poque m\u00e9di\u00e9vale, la ville de Kyoto compte de nombreuses destinations li\u00e9es \u00e0 la composition de la po\u00e9sie renga. Le palais imp\u00e9rial de Kyoto est l&#8217;un des sites historiques les mieux pr\u00e9serv\u00e9s de tout le Japon et comprend un incroyable parc qui abrite un bosquet de cerisiers pleureurs. Par ailleurs, les innombrables temples et sanctuaires de la ville refl\u00e8tent parfaitement l&#8217;esprit communautaire du renga.<\/span><span data-contrast=\"none\">\u00a0Le\u00a0<\/span><a href=\"https:\/\/www.japan.travel\/en\/spot\/1152\/\"><span data-contrast=\"none\">temple Kinkakuji<\/span><\/a><span data-contrast=\"none\">, un lieu de culte du XIVe si\u00e8cle connu pour ses feuilles d&#8217;or \u00e0 l&#8217;ext\u00e9rieur, est l&#8217;un des exemples les plus remarquables de l&#8217;architecture m\u00e9di\u00e9vale japonaise. Il est inscrit au patrimoine mondial de l&#8217;UNESCO et accueille des milliers de touristes chaque ann\u00e9e.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<h2>Haiga<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5439 size-full\" src=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_1909221886.jpg\" alt=\"Woman painting\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_1909221886.jpg 1000w, https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/Shutterstock_1909221886-300x180.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span data-contrast=\"none\">Le ha\u00efga est l&#8217;une des formes les plus frappantes de la po\u00e9sie japonaise, un mariage entre la forme litt\u00e9raire des ha\u00efkus et les peintures minimalistes. Les ha\u00efgas sont con\u00e7us comme une conversation entre l&#8217;art visuel et l&#8217;art \u00e9crit. Les peintures qui accompagnent les ha\u00efkus dans les ha\u00efgas sont souvent amusantes et l\u00e9g\u00e8res, m\u00eame si le sujet du ha\u00efku est plus s\u00e9rieux. De cette mani\u00e8re, les deux se compl\u00e8tent et racontent leurs propres histoires.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Les po\u00e8tes modernes d\u00e9sireux de cr\u00e9er des ha\u00efgas ont puis\u00e9 leur inspiration dans d&#8217;innombrables lieux du pays du Soleil-Levant. Les zones baign\u00e9es par une beaut\u00e9 naturelle sont particuli\u00e8rement puissantes pour les po\u00e8tes qui esp\u00e8rent composer le haiga parfait. Hakone, ville de montagne connue pour ses sources d&#8217;eau chaude et ses vues imprenables sur le lac Ashinoko et le mont Fuji, est une destination particuli\u00e8rement merveilleuse pour ceux qui esp\u00e8rent comprendre le pouvoir artistique du haiga. Les paysages marins graves de la p\u00e9ninsule d&#8217;Izu offrent \u00e9galement un aper\u00e7u \u00e9tonnant de l&#8217;\u00e9laboration du haiga et constituent un excellent exemple de la beaut\u00e9 maritime du Japon.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p>\n<p><strong><em>Vous pourriez \u00e9galement appr\u00e9cier: <a href=\"https:\/\/www.cheapoair.ca\/getting-there\/friandises-du-monde-le-voyage-dun-amateur-de-bonbons-a-travers-les-saveurs-du-monde\/\">FRIANDISES DU MONDE: LE VOYAGE D&#8217;UN AMATEUR DE BONBONS \u00c0 TRAVERS LES SAVEURS DU MONDE<\/a>\u00a0<\/em><\/strong><\/p>\n<h2>Senryu<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5464\" src=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/shutterstock_2139123285.jpg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/shutterstock_2139123285.jpg 1000w, https:\/\/www.cheapoair.ca\/getting-there\/wp-content\/uploads\/2024\/04\/shutterstock_2139123285-300x169.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span data-contrast=\"none\">Suivant le sch\u00e9ma de composition traditionnel 5-7-5, le senryu est le petit fr\u00e8re humoristique du ha\u00efku. Alors que les ha\u00efkus se concentrent sur le monde naturel, les senryus se tournent vers l&#8217;intime\u00a0et mettent l&#8217;accent sur les excentricit\u00e9s de l&#8217;exp\u00e9rience humaine. Satiriques et pleins d&#8217;une bonne dose d&#8217;ironie, les senryus sont souvent consid\u00e9r\u00e9s comme plus cyniques dans leur sujet et sont connus pour leur humour noir et mordant. Bien qu&#8217;ils soient tr\u00e8s appr\u00e9ci\u00e9s des po\u00e8tes modernes, les premi\u00e8res compositions de senryu remontent au XVIIe si\u00e8cle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">\u00c9tant donn\u00e9 que les senryus traitent beaucoup de la nature humaine et de la psychologie, les centres urbains du Japon sont les endroits id\u00e9aux pour comprendre leur vision sarcastique de la vie moderne. Peu de villes permettent \u00e0 ceux qui visitent le\u00a0<\/span><a href=\"https:\/\/www.cheapoair.com\/flights\/cheap-flights-to-japan-jp\"><span data-contrast=\"none\">Japon<\/span><\/a><span data-contrast=\"none\">\u00a0d&#8217;exp\u00e9rimenter l&#8217;agitation de la vie japonaise autant que Tokyo. Ville moderne qui n&#8217;en oublie pas moins le pass\u00e9 historique du Japon,\u00a0<\/span><a href=\"https:\/\/www.cheapoair.com\/flights\/cheap-flights-to-tokyo-tyo-japan\"><span data-contrast=\"none\">Tokyo<\/span><\/a><span data-contrast=\"none\">\u00a0est l&#8217;endroit id\u00e9al pour observer les gens et \u00e9crire son propre senryu. La ville abrite \u00e9galement une communaut\u00e9 exceptionnelle d&#8217;humoristes qui savent comment faire une blague et faire rire le public des bizarreries et des imperfections du monde moderne.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<h2><i>Questions fr\u00e9quemment pos\u00e9es :<\/i><\/h2>\n<p><b><span data-contrast=\"none\">Q : Comment les visiteurs de Matsuyama peuvent-ils s&#8217;immerger davantage dans l&#8217;histoire du ha\u00efku au-del\u00e0 de la visite du mus\u00e9e de Masaoka Shiki?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"none\">R : \u00c0 Matsuyama, les visiteurs peuvent participer \u00e0 des ateliers de ha\u00efku anim\u00e9s par des po\u00e8tes locaux, ce qui leur permet d&#8217;acqu\u00e9rir une exp\u00e9rience pratique dans la cr\u00e9ation de leurs propres ha\u00efkus et d&#8217;approfondir leur connaissance des techniques de cette forme d&#8217;art.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Q : Outre le palais Heijo et le jardin Isui-en, y a-t-il d&#8217;autres sites \u00e0 Nara qui offrent un aper\u00e7u de la culture po\u00e9tique japonaise de l&#8217;\u00e8re classique ?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"none\">R : Oui, les voyageurs peuvent explorer le Mus\u00e9e national de Nara, qui accueille souvent des expositions consacr\u00e9es \u00e0 des manuscrits anciens et \u00e0 des objets li\u00e9s \u00e0 la po\u00e9sie japonaise, ce qui permet de mieux comprendre le contexte culturel entourant le tanka et d&#8217;autres formes po\u00e9tiques.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Q : Existe-t-il \u00e0 Kyoto des destinations moins connues associ\u00e9es \u00e0 la composition de la po\u00e9sie renga?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"none\">R : Les voyageurs int\u00e9ress\u00e9s par la po\u00e9sie renga peuvent visiter la for\u00eat de bambous du temple Tenryuji, qui a inspir\u00e9 de nombreux po\u00e8tes tout au long de l&#8217;histoire gr\u00e2ce \u00e0 son atmosph\u00e8re paisible, offrant un cadre calme propice \u00e0 la contemplation et \u00e0 la cr\u00e9ativit\u00e9.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Q : O\u00f9 les visiteurs peuvent-ils trouver des artistes locaux sp\u00e9cialis\u00e9s dans la cr\u00e9ation de haiga \u00e0 Hakone et dans la p\u00e9ninsule d&#8217;Izu?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"none\">R : \u00c0 Hakone et dans la p\u00e9ninsule d&#8217;Izu, les voyageurs peuvent visiter des galeries d&#8217;art traditionnelles et des studios qui exposent les \u0153uvres d&#8217;artistes de ha\u00efga contemporains, ce qui leur donne l&#8217;occasion d&#8217;interagir avec la communaut\u00e9 artistique locale et de d\u00e9couvrir leur processus cr\u00e9atif de premi\u00e8re main.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Q : Existe-t-il \u00e0 Tokyo des zones ou des quartiers particuliers connus pour leur lien avec la po\u00e9sie senryu?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"none\">R : Oui, les visiteurs peuvent explorer des zones comme Asakusa et Yanaka, connues pour leur charme traditionnel et leurs rues historiques, qui ont inspir\u00e9 de nombreux po\u00e8tes senryu par leur ambiance nostalgique et leur importance culturelle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><i><span data-contrast=\"none\">Connaissez-vous ces genres de po\u00e9sie japonaise ?<\/span><\/i><\/b><span data-contrast=\"none\">\u00a0<\/span><b><i><span data-contrast=\"none\">Dites-le-nous dans les commentaires ci-dessous!<\/span><\/i><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Japon est l&#8217;un des plus grands bastions d&#8217;expression culturelle et artistique au monde. L&#8217;une des prouesses artistiques les plus reconnaissables de la culture japonaise est la po\u00e9sie, un art qui \u00e9volue et se perfectionne depuis plus de mille ans. Si le ha\u00efku est la forme la plus connue de la po\u00e9sie japonaise, ce genre [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":5538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104],"tags":[],"class_list":{"0":"post-5536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-en-francais"},"_links":{"self":[{"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/posts\/5536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/comments?post=5536"}],"version-history":[{"count":2,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/posts\/5536\/revisions"}],"predecessor-version":[{"id":5539,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/posts\/5536\/revisions\/5539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/media\/5538"}],"wp:attachment":[{"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/media?parent=5536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/categories?post=5536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cheapoair.ca\/getting-there\/wp-json\/wp\/v2\/tags?post=5536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}